{"id":1779,"date":"2020-10-21T09:15:38","date_gmt":"2020-10-21T09:15:38","guid":{"rendered":"http:\/\/wordpress.iqonic.design\/kivicare\/?page_id=1779"},"modified":"2025-05-04T23:08:08","modified_gmt":"2025-05-04T23:08:08","slug":"our-team","status":"publish","type":"page","link":"https:\/\/backup.the360clinics.com\/the360clinics\/our-team\/","title":{"rendered":"Our Team"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1779\" class=\"elementor elementor-1779\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-3dc30d72 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3dc30d72\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e6d4a55 layouts-column-align-inherit layouts-section-position-none\" data-id=\"e6d4a55\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-6136dd79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6136dd79\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5d9244c7 layouts-column-align-inherit layouts-section-position-none\" data-id=\"5d9244c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-20b20026 elementor-widget elementor-widget-section_title\" data-id=\"20b20026\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"iq-title-box iq-title-box-1 iq-befor-line\">\n\t\t<div class=\"iq-title-icon\">\n\t\t\t\t\t<\/div>\n\t\t<span class=\"iq-subtitle\">Doctors<\/span>\n\t\t<h2 class=\"iq-title iq-heading-title\">\n\t\t\tBest Specialist Doctors\t\t<\/h2>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-6444541 elementor-absolute elementor-hidden-tablet elementor-hidden-phone elementor-widget-tablet__width-initial elementor-widget elementor-widget-Iq_scrolling_text\" data-id=\"6444541\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"Iq_scrolling_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"scrolling-text\"  id=\"iq-text6836676596a97d293146a1\">\n\n    <div class=\"iq-test\">\n        Our Team    <\/div>\n\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-39e93e36 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39e93e36\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-48bf5269 layouts-column-align-inherit layouts-section-position-none\" data-id=\"48bf5269\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-ef7ef14 elementor-widget elementor-widget-team_tab\" data-id=\"ef7ef14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"team_tab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"features-34\" class=\"kivicare-team-tab\">\n\n    <div class=\"row\">\n        <div class=\"col-lg-12 kivicare_filters\">\n            <ul class=\"nav kivicare-team-tab-nav justify-content-center\" id=\"myTab-34\" role=\"tablist\">\n                                <li>\n                    <a class=\"nav-link active show\" id=\"all-tab-34\" data-bs-toggle=\"tab\" href=\"#all-34\" role=\"tab\" aria-selected=\"true\"><span>All<\/span>\n                    <\/a>\n                <\/li>\n                                    <li><a class=\"nav-link\" id=\"academic-advisor-tab-34\" data-bs-toggle=\"tab\" href=\"#academic-advisor-34\" role=\"tab\"><span>Academic Advisor<\/span><\/a><\/li>\n                                    <li><a class=\"nav-link\" id=\"biophysical-tab-34\" data-bs-toggle=\"tab\" href=\"#biophysical-34\" role=\"tab\"><span>Biophysical<\/span><\/a><\/li>\n                                    <li><a class=\"nav-link\" id=\"business-development-tab-34\" data-bs-toggle=\"tab\" href=\"#business-development-34\" role=\"tab\"><span>Business Development<\/span><\/a><\/li>\n                                    <li><a class=\"nav-link\" id=\"clinical-psychologist-tab-34\" data-bs-toggle=\"tab\" href=\"#clinical-psychologist-34\" role=\"tab\"><span>Clinical Psychologist<\/span><\/a><\/li>\n                                    <li><a class=\"nav-link\" id=\"neuropsychology-tab-34\" data-bs-toggle=\"tab\" href=\"#neuropsychology-34\" role=\"tab\"><span>Neuropsychology<\/span><\/a><\/li>\n                                    <li><a class=\"nav-link\" id=\"psychiatrist-tab-34\" data-bs-toggle=\"tab\" href=\"#psychiatrist-34\" role=\"tab\"><span>Psychiatrist<\/span><\/a><\/li>\n                                    <li><a class=\"nav-link\" id=\"psychologist-tab-34\" data-bs-toggle=\"tab\" href=\"#psychologist-34\" role=\"tab\"><span>Psychologist<\/span><\/a><\/li>\n                                    <li><a class=\"nav-link\" id=\"psychotherapist-tab-34\" data-bs-toggle=\"tab\" href=\"#psychotherapist-34\" role=\"tab\"><span>Psychotherapist<\/span><\/a><\/li>\n                                    <li><a class=\"nav-link\" id=\"speech-therapist-tab-34\" data-bs-toggle=\"tab\" href=\"#speech-therapist-34\" role=\"tab\"><span>Speech Therapist<\/span><\/a><\/li>\n                            <\/ul>\n        <\/div>\n    <\/div>\n\n    \n    <div class=\"tab-content iq-team iq-team-style-1\">\n        <div class=\"tab-pane active\" id=\"all-34\">\n            <div class=\"row\">\n\n                                    <div class=\"col-lg-4 col-md-6\">\n                        <div class=\"iq-team-blog animated fadeInUp psychologist blogBox moreBox\">\n                                                            <div class=\"iq-team-img\">\n                                    <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Heba-Tarek-Naguib.png\" alt=\"iqonic-casestudy\"\/>                                <\/div>\n                                                        <div class=\"share iq-team-social\">\n                                <ul>\n                                                                    <\/ul>\n                            <\/div>\n                            <div class=\"iq-team-info\">\n                                <div class=\"iq-team-main-detail\">\n                                    <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/heba-tarek-naguib\/\">\n                                        <h5 class=\"member-text iq-heading-title\">\n                                            Heba Tarek Naguib                                        <\/h5>\n                                    <\/a>\n                                    <span class=\"iq-specialized\">\n                                        Psychologist                                    <\/span>\n\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"col-lg-4 col-md-6\">\n                        <div class=\"iq-team-blog animated fadeInUp speech-therapist blogBox moreBox\">\n                                                            <div class=\"iq-team-img\">\n                                    <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Aya-Mohamed.png\" alt=\"iqonic-casestudy\"\/>                                <\/div>\n                                                        <div class=\"share iq-team-social\">\n                                <ul>\n                                                                    <\/ul>\n                            <\/div>\n                            <div class=\"iq-team-info\">\n                                <div class=\"iq-team-main-detail\">\n                                    <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/aya-mohamed\/\">\n                                        <h5 class=\"member-text iq-heading-title\">\n                                            Aya Mohamed                                        <\/h5>\n                                    <\/a>\n                                    <span class=\"iq-specialized\">\n                                        Speech Therapist                                    <\/span>\n\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"col-lg-4 col-md-6\">\n                        <div class=\"iq-team-blog animated fadeInUp speech-therapist blogBox moreBox\">\n                                                            <div class=\"iq-team-img\">\n                                    <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Shaimaa-Hassan.png\" alt=\"iqonic-casestudy\"\/>                                <\/div>\n                                                        <div class=\"share iq-team-social\">\n                                <ul>\n                                                                    <\/ul>\n                            <\/div>\n                            <div class=\"iq-team-info\">\n                                <div class=\"iq-team-main-detail\">\n                                    <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/shaimaa-hassan\/\">\n                                        <h5 class=\"member-text iq-heading-title\">\n                                            Shaimaa Hassan                                        <\/h5>\n                                    <\/a>\n                                    <span class=\"iq-specialized\">\n                                        Speech Therapist                                    <\/span>\n\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"col-lg-4 col-md-6\">\n                        <div class=\"iq-team-blog animated fadeInUp neuropsychology blogBox moreBox\">\n                                                            <div class=\"iq-team-img\">\n                                    <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Yassmin-Kordy.jpeg\" alt=\"iqonic-casestudy\"\/>                                <\/div>\n                                                        <div class=\"share iq-team-social\">\n                                <ul>\n                                                                    <\/ul>\n                            <\/div>\n                            <div class=\"iq-team-info\">\n                                <div class=\"iq-team-main-detail\">\n                                    <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/yassmin-kordy\/\">\n                                        <h5 class=\"member-text iq-heading-title\">\n                                            Yassmin Kordy                                        <\/h5>\n                                    <\/a>\n                                    <span class=\"iq-specialized\">\n                                        Neuropsychology                                    <\/span>\n\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"col-lg-4 col-md-6\">\n                        <div class=\"iq-team-blog animated fadeInUp neuropsychology blogBox moreBox\">\n                                                            <div class=\"iq-team-img\">\n                                    <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Mustafa-Hassaballah.png\" alt=\"iqonic-casestudy\"\/>                                <\/div>\n                                                        <div class=\"share iq-team-social\">\n                                <ul>\n                                                                    <\/ul>\n                            <\/div>\n                            <div class=\"iq-team-info\">\n                                <div class=\"iq-team-main-detail\">\n                                    <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/mustafa-hassaballah\/\">\n                                        <h5 class=\"member-text iq-heading-title\">\n                                            Mustafa Hassaballah                                        <\/h5>\n                                    <\/a>\n                                    <span class=\"iq-specialized\">\n                                        Neuropsychology                                    <\/span>\n\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"col-lg-4 col-md-6\">\n                        <div class=\"iq-team-blog animated fadeInUp psychotherapist blogBox moreBox\">\n                                                            <div class=\"iq-team-img\">\n                                    <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Nada-Nakhla.jpeg\" alt=\"iqonic-casestudy\"\/>                                <\/div>\n                                                        <div class=\"share iq-team-social\">\n                                <ul>\n                                                                    <\/ul>\n                            <\/div>\n                            <div class=\"iq-team-info\">\n                                <div class=\"iq-team-main-detail\">\n                                    <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/nada-nakhla\/\">\n                                        <h5 class=\"member-text iq-heading-title\">\n                                            Nada Nakhla                                        <\/h5>\n                                    <\/a>\n                                    <span class=\"iq-specialized\">\n                                        Psychotherapist                                    <\/span>\n\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"col-lg-4 col-md-6\">\n                        <div class=\"iq-team-blog animated fadeInUp neuropsychology blogBox moreBox\">\n                                                            <div class=\"iq-team-img\">\n                                    <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Salma-El-Behary.jpeg\" alt=\"iqonic-casestudy\"\/>                                <\/div>\n                                                        <div class=\"share iq-team-social\">\n                                <ul>\n                                                                    <\/ul>\n                            <\/div>\n                            <div class=\"iq-team-info\">\n                                <div class=\"iq-team-main-detail\">\n                                    <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/salma-el-behary\/\">\n                                        <h5 class=\"member-text iq-heading-title\">\n                                            Salma El Behary                                        <\/h5>\n                                    <\/a>\n                                    <span class=\"iq-specialized\">\n                                        Neuropsychology                                    <\/span>\n\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"col-lg-4 col-md-6\">\n                        <div class=\"iq-team-blog animated fadeInUp biophysical blogBox moreBox\">\n                                                            <div class=\"iq-team-img\">\n                                    <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Malak-El-Dessouki.jpeg\" alt=\"iqonic-casestudy\"\/>                                <\/div>\n                                                        <div class=\"share iq-team-social\">\n                                <ul>\n                                                                    <\/ul>\n                            <\/div>\n                            <div class=\"iq-team-info\">\n                                <div class=\"iq-team-main-detail\">\n                                    <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/malak-el-dessouki\/\">\n                                        <h5 class=\"member-text iq-heading-title\">\n                                            Malak El Dessouki                                        <\/h5>\n                                    <\/a>\n                                    <span class=\"iq-specialized\">\n                                        Biophysical                                    <\/span>\n\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"col-lg-4 col-md-6\">\n                        <div class=\"iq-team-blog animated fadeInUp clinical-psychologist blogBox moreBox\">\n                                                            <div class=\"iq-team-img\">\n                                    <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Shahd-Fouad.png\" alt=\"iqonic-casestudy\"\/>                                <\/div>\n                                                        <div class=\"share iq-team-social\">\n                                <ul>\n                                                                    <\/ul>\n                            <\/div>\n                            <div class=\"iq-team-info\">\n                                <div class=\"iq-team-main-detail\">\n                                    <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/shahd-fouad\/\">\n                                        <h5 class=\"member-text iq-heading-title\">\n                                            Shahd Fouad                                        <\/h5>\n                                    <\/a>\n                                    <span class=\"iq-specialized\">\n                                        Clinical Psychologist                                    <\/span>\n\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"col-lg-4 col-md-6\">\n                        <div class=\"iq-team-blog animated fadeInUp academic-advisor blogBox moreBox\">\n                                                            <div class=\"iq-team-img\">\n                                    <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Aya-Azzam.png\" alt=\"iqonic-casestudy\"\/>                                <\/div>\n                                                        <div class=\"share iq-team-social\">\n                                <ul>\n                                                                    <\/ul>\n                            <\/div>\n                            <div class=\"iq-team-info\">\n                                <div class=\"iq-team-main-detail\">\n                                    <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/aya-azzam\/\">\n                                        <h5 class=\"member-text iq-heading-title\">\n                                            Aya Azzam                                        <\/h5>\n                                    <\/a>\n                                    <span class=\"iq-specialized\">\n                                        Academic Advisor                                    <\/span>\n\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"col-lg-4 col-md-6\">\n                        <div class=\"iq-team-blog animated fadeInUp neuropsychology blogBox moreBox\">\n                                                            <div class=\"iq-team-img\">\n                                    <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Ahmed-Hassan.png\" alt=\"iqonic-casestudy\"\/>                                <\/div>\n                                                        <div class=\"share iq-team-social\">\n                                <ul>\n                                                                    <\/ul>\n                            <\/div>\n                            <div class=\"iq-team-info\">\n                                <div class=\"iq-team-main-detail\">\n                                    <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/ahmed-hassan\/\">\n                                        <h5 class=\"member-text iq-heading-title\">\n                                            Ahmed Hassan                                        <\/h5>\n                                    <\/a>\n                                    <span class=\"iq-specialized\">\n                                        Neuropsychology                                    <\/span>\n\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"col-lg-4 col-md-6\">\n                        <div class=\"iq-team-blog animated fadeInUp business-development blogBox moreBox\">\n                                                            <div class=\"iq-team-img\">\n                                    <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/04\/424599951_780483447443055_4865742799589225973_n.jpg\" alt=\"iqonic-casestudy\"\/>                                <\/div>\n                                                        <div class=\"share iq-team-social\">\n                                <ul>\n                                                                    <\/ul>\n                            <\/div>\n                            <div class=\"iq-team-info\">\n                                <div class=\"iq-team-main-detail\">\n                                    <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/nadine-el-shafei\/\">\n                                        <h5 class=\"member-text iq-heading-title\">\n                                            Nadine El Shafei                                        <\/h5>\n                                    <\/a>\n                                    <span class=\"iq-specialized\">\n                                        Business Development                                    <\/span>\n\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"col-lg-4 col-md-6\">\n                        <div class=\"iq-team-blog animated fadeInUp business-development blogBox moreBox\">\n                                                            <div class=\"iq-team-img\">\n                                    <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/04\/Mohamed-El-Dakkak.png\" alt=\"iqonic-casestudy\"\/>                                <\/div>\n                                                        <div class=\"share iq-team-social\">\n                                <ul>\n                                                                    <\/ul>\n                            <\/div>\n                            <div class=\"iq-team-info\">\n                                <div class=\"iq-team-main-detail\">\n                                    <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/mohamed-el-dakkak\/\">\n                                        <h5 class=\"member-text iq-heading-title\">\n                                            Mohamed El Dakkak                                        <\/h5>\n                                    <\/a>\n                                    <span class=\"iq-specialized\">\n                                        Business Development                                    <\/span>\n\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"col-lg-4 col-md-6\">\n                        <div class=\"iq-team-blog animated fadeInUp psychiatrist blogBox moreBox\">\n                                                            <div class=\"iq-team-img\">\n                                    <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/04\/Ali-Bahnasy.jpg\" alt=\"iqonic-casestudy\"\/>                                <\/div>\n                                                        <div class=\"share iq-team-social\">\n                                <ul>\n                                                                    <\/ul>\n                            <\/div>\n                            <div class=\"iq-team-info\">\n                                <div class=\"iq-team-main-detail\">\n                                    <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/ali-bahnasy\/\">\n                                        <h5 class=\"member-text iq-heading-title\">\n                                            Ali Bahnasy                                        <\/h5>\n                                    <\/a>\n                                    <span class=\"iq-specialized\">\n                                        Psychiatrist                                    <\/span>\n\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"col-lg-4 col-md-6\">\n                        <div class=\"iq-team-blog animated fadeInUp neuropsychology blogBox moreBox\">\n                                                            <div class=\"iq-team-img\">\n                                    <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/04\/424606832_780481634109903_6612487551017199223_n.jpg\" alt=\"iqonic-casestudy\"\/>                                <\/div>\n                                                        <div class=\"share iq-team-social\">\n                                <ul>\n                                                                    <\/ul>\n                            <\/div>\n                            <div class=\"iq-team-info\">\n                                <div class=\"iq-team-main-detail\">\n                                    <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/zeina-el-rayes\/\">\n                                        <h5 class=\"member-text iq-heading-title\">\n                                            Zeina El Rayes                                        <\/h5>\n                                    <\/a>\n                                    <span class=\"iq-specialized\">\n                                        Neuropsychology                                    <\/span>\n\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                            <\/div>\n        <\/div>\n                    <div class=\"tab-pane\" id=\"academic-advisor-34\">\n                <div class=\"row\">\n\n                                            <div class=\"col-lg-4 col-md-6\">\n                            <div class=\"iq-team-blog animated fadeInUp academic-advisor blogBox moreBox\">\n                            \n                                                                    <div class=\"kivicare-project-image\">\n                                        <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Aya-Azzam.png\" alt=\"iqonic-casestudy\"\/>                                    <\/div>\n                                \n                                <div class=\"share iq-team-social\">\n                                    <ul>\n                                                                            <\/ul>\n                                <\/div>\n                                <div class=\"iq-team-info\">\n                                    <div class=\"iq-team-main-detail\">\n                                        <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/aya-azzam\/\">\n                                            <h5 class=\"member-text iq-heading-title\">\n                                                Aya Azzam                                            <\/h5>\n                                        <\/a>\n                                        <span class=\"iq-specialized\">\n                                            Academic Advisor                                        <\/span>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                           <div class=\"tab-pane\" id=\"biophysical-34\">\n                <div class=\"row\">\n\n                                            <div class=\"col-lg-4 col-md-6\">\n                            <div class=\"iq-team-blog animated fadeInUp biophysical blogBox moreBox\">\n                            \n                                                                    <div class=\"kivicare-project-image\">\n                                        <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Malak-El-Dessouki.jpeg\" alt=\"iqonic-casestudy\"\/>                                    <\/div>\n                                \n                                <div class=\"share iq-team-social\">\n                                    <ul>\n                                                                            <\/ul>\n                                <\/div>\n                                <div class=\"iq-team-info\">\n                                    <div class=\"iq-team-main-detail\">\n                                        <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/malak-el-dessouki\/\">\n                                            <h5 class=\"member-text iq-heading-title\">\n                                                Malak El Dessouki                                            <\/h5>\n                                        <\/a>\n                                        <span class=\"iq-specialized\">\n                                            Biophysical                                        <\/span>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                           <div class=\"tab-pane\" id=\"business-development-34\">\n                <div class=\"row\">\n\n                                            <div class=\"col-lg-4 col-md-6\">\n                            <div class=\"iq-team-blog animated fadeInUp business-development blogBox moreBox\">\n                            \n                                                                    <div class=\"kivicare-project-image\">\n                                        <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/04\/424599951_780483447443055_4865742799589225973_n.jpg\" alt=\"iqonic-casestudy\"\/>                                    <\/div>\n                                \n                                <div class=\"share iq-team-social\">\n                                    <ul>\n                                                                            <\/ul>\n                                <\/div>\n                                <div class=\"iq-team-info\">\n                                    <div class=\"iq-team-main-detail\">\n                                        <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/nadine-el-shafei\/\">\n                                            <h5 class=\"member-text iq-heading-title\">\n                                                Nadine El Shafei                                            <\/h5>\n                                        <\/a>\n                                        <span class=\"iq-specialized\">\n                                            Business Development                                        <\/span>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                            <div class=\"col-lg-4 col-md-6\">\n                            <div class=\"iq-team-blog animated fadeInUp business-development blogBox moreBox\">\n                            \n                                                                    <div class=\"kivicare-project-image\">\n                                        <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/04\/Mohamed-El-Dakkak.png\" alt=\"iqonic-casestudy\"\/>                                    <\/div>\n                                \n                                <div class=\"share iq-team-social\">\n                                    <ul>\n                                                                            <\/ul>\n                                <\/div>\n                                <div class=\"iq-team-info\">\n                                    <div class=\"iq-team-main-detail\">\n                                        <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/mohamed-el-dakkak\/\">\n                                            <h5 class=\"member-text iq-heading-title\">\n                                                Mohamed El Dakkak                                            <\/h5>\n                                        <\/a>\n                                        <span class=\"iq-specialized\">\n                                            Business Development                                        <\/span>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                           <div class=\"tab-pane\" id=\"clinical-psychologist-34\">\n                <div class=\"row\">\n\n                                            <div class=\"col-lg-4 col-md-6\">\n                            <div class=\"iq-team-blog animated fadeInUp clinical-psychologist blogBox moreBox\">\n                            \n                                                                    <div class=\"kivicare-project-image\">\n                                        <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Shahd-Fouad.png\" alt=\"iqonic-casestudy\"\/>                                    <\/div>\n                                \n                                <div class=\"share iq-team-social\">\n                                    <ul>\n                                                                            <\/ul>\n                                <\/div>\n                                <div class=\"iq-team-info\">\n                                    <div class=\"iq-team-main-detail\">\n                                        <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/shahd-fouad\/\">\n                                            <h5 class=\"member-text iq-heading-title\">\n                                                Shahd Fouad                                            <\/h5>\n                                        <\/a>\n                                        <span class=\"iq-specialized\">\n                                            Clinical Psychologist                                        <\/span>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                           <div class=\"tab-pane\" id=\"neuropsychology-34\">\n                <div class=\"row\">\n\n                                            <div class=\"col-lg-4 col-md-6\">\n                            <div class=\"iq-team-blog animated fadeInUp neuropsychology blogBox moreBox\">\n                            \n                                                                    <div class=\"kivicare-project-image\">\n                                        <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Yassmin-Kordy.jpeg\" alt=\"iqonic-casestudy\"\/>                                    <\/div>\n                                \n                                <div class=\"share iq-team-social\">\n                                    <ul>\n                                                                            <\/ul>\n                                <\/div>\n                                <div class=\"iq-team-info\">\n                                    <div class=\"iq-team-main-detail\">\n                                        <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/yassmin-kordy\/\">\n                                            <h5 class=\"member-text iq-heading-title\">\n                                                Yassmin Kordy                                            <\/h5>\n                                        <\/a>\n                                        <span class=\"iq-specialized\">\n                                            Neuropsychology                                        <\/span>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                            <div class=\"col-lg-4 col-md-6\">\n                            <div class=\"iq-team-blog animated fadeInUp neuropsychology blogBox moreBox\">\n                            \n                                                                    <div class=\"kivicare-project-image\">\n                                        <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Mustafa-Hassaballah.png\" alt=\"iqonic-casestudy\"\/>                                    <\/div>\n                                \n                                <div class=\"share iq-team-social\">\n                                    <ul>\n                                                                            <\/ul>\n                                <\/div>\n                                <div class=\"iq-team-info\">\n                                    <div class=\"iq-team-main-detail\">\n                                        <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/mustafa-hassaballah\/\">\n                                            <h5 class=\"member-text iq-heading-title\">\n                                                Mustafa Hassaballah                                            <\/h5>\n                                        <\/a>\n                                        <span class=\"iq-specialized\">\n                                            Neuropsychology                                        <\/span>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                            <div class=\"col-lg-4 col-md-6\">\n                            <div class=\"iq-team-blog animated fadeInUp neuropsychology blogBox moreBox\">\n                            \n                                                                    <div class=\"kivicare-project-image\">\n                                        <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Salma-El-Behary.jpeg\" alt=\"iqonic-casestudy\"\/>                                    <\/div>\n                                \n                                <div class=\"share iq-team-social\">\n                                    <ul>\n                                                                            <\/ul>\n                                <\/div>\n                                <div class=\"iq-team-info\">\n                                    <div class=\"iq-team-main-detail\">\n                                        <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/salma-el-behary\/\">\n                                            <h5 class=\"member-text iq-heading-title\">\n                                                Salma El Behary                                            <\/h5>\n                                        <\/a>\n                                        <span class=\"iq-specialized\">\n                                            Neuropsychology                                        <\/span>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                            <div class=\"col-lg-4 col-md-6\">\n                            <div class=\"iq-team-blog animated fadeInUp neuropsychology blogBox moreBox\">\n                            \n                                                                    <div class=\"kivicare-project-image\">\n                                        <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Ahmed-Hassan.png\" alt=\"iqonic-casestudy\"\/>                                    <\/div>\n                                \n                                <div class=\"share iq-team-social\">\n                                    <ul>\n                                                                            <\/ul>\n                                <\/div>\n                                <div class=\"iq-team-info\">\n                                    <div class=\"iq-team-main-detail\">\n                                        <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/ahmed-hassan\/\">\n                                            <h5 class=\"member-text iq-heading-title\">\n                                                Ahmed Hassan                                            <\/h5>\n                                        <\/a>\n                                        <span class=\"iq-specialized\">\n                                            Neuropsychology                                        <\/span>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                            <div class=\"col-lg-4 col-md-6\">\n                            <div class=\"iq-team-blog animated fadeInUp neuropsychology blogBox moreBox\">\n                            \n                                                                    <div class=\"kivicare-project-image\">\n                                        <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/04\/424606832_780481634109903_6612487551017199223_n.jpg\" alt=\"iqonic-casestudy\"\/>                                    <\/div>\n                                \n                                <div class=\"share iq-team-social\">\n                                    <ul>\n                                                                            <\/ul>\n                                <\/div>\n                                <div class=\"iq-team-info\">\n                                    <div class=\"iq-team-main-detail\">\n                                        <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/zeina-el-rayes\/\">\n                                            <h5 class=\"member-text iq-heading-title\">\n                                                Zeina El Rayes                                            <\/h5>\n                                        <\/a>\n                                        <span class=\"iq-specialized\">\n                                            Neuropsychology                                        <\/span>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                           <div class=\"tab-pane\" id=\"psychiatrist-34\">\n                <div class=\"row\">\n\n                                            <div class=\"col-lg-4 col-md-6\">\n                            <div class=\"iq-team-blog animated fadeInUp psychiatrist blogBox moreBox\">\n                            \n                                                                    <div class=\"kivicare-project-image\">\n                                        <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/04\/Ali-Bahnasy.jpg\" alt=\"iqonic-casestudy\"\/>                                    <\/div>\n                                \n                                <div class=\"share iq-team-social\">\n                                    <ul>\n                                                                            <\/ul>\n                                <\/div>\n                                <div class=\"iq-team-info\">\n                                    <div class=\"iq-team-main-detail\">\n                                        <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/ali-bahnasy\/\">\n                                            <h5 class=\"member-text iq-heading-title\">\n                                                Ali Bahnasy                                            <\/h5>\n                                        <\/a>\n                                        <span class=\"iq-specialized\">\n                                            Psychiatrist                                        <\/span>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                           <div class=\"tab-pane\" id=\"psychologist-34\">\n                <div class=\"row\">\n\n                                            <div class=\"col-lg-4 col-md-6\">\n                            <div class=\"iq-team-blog animated fadeInUp psychologist blogBox moreBox\">\n                            \n                                                                    <div class=\"kivicare-project-image\">\n                                        <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Heba-Tarek-Naguib.png\" alt=\"iqonic-casestudy\"\/>                                    <\/div>\n                                \n                                <div class=\"share iq-team-social\">\n                                    <ul>\n                                                                            <\/ul>\n                                <\/div>\n                                <div class=\"iq-team-info\">\n                                    <div class=\"iq-team-main-detail\">\n                                        <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/heba-tarek-naguib\/\">\n                                            <h5 class=\"member-text iq-heading-title\">\n                                                Heba Tarek Naguib                                            <\/h5>\n                                        <\/a>\n                                        <span class=\"iq-specialized\">\n                                            Psychologist                                        <\/span>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                           <div class=\"tab-pane\" id=\"psychotherapist-34\">\n                <div class=\"row\">\n\n                                            <div class=\"col-lg-4 col-md-6\">\n                            <div class=\"iq-team-blog animated fadeInUp psychotherapist blogBox moreBox\">\n                            \n                                                                    <div class=\"kivicare-project-image\">\n                                        <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Nada-Nakhla.jpeg\" alt=\"iqonic-casestudy\"\/>                                    <\/div>\n                                \n                                <div class=\"share iq-team-social\">\n                                    <ul>\n                                                                            <\/ul>\n                                <\/div>\n                                <div class=\"iq-team-info\">\n                                    <div class=\"iq-team-main-detail\">\n                                        <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/nada-nakhla\/\">\n                                            <h5 class=\"member-text iq-heading-title\">\n                                                Nada Nakhla                                            <\/h5>\n                                        <\/a>\n                                        <span class=\"iq-specialized\">\n                                            Psychotherapist                                        <\/span>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                           <div class=\"tab-pane\" id=\"speech-therapist-34\">\n                <div class=\"row\">\n\n                                            <div class=\"col-lg-4 col-md-6\">\n                            <div class=\"iq-team-blog animated fadeInUp speech-therapist blogBox moreBox\">\n                            \n                                                                    <div class=\"kivicare-project-image\">\n                                        <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Aya-Mohamed.png\" alt=\"iqonic-casestudy\"\/>                                    <\/div>\n                                \n                                <div class=\"share iq-team-social\">\n                                    <ul>\n                                                                            <\/ul>\n                                <\/div>\n                                <div class=\"iq-team-info\">\n                                    <div class=\"iq-team-main-detail\">\n                                        <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/aya-mohamed\/\">\n                                            <h5 class=\"member-text iq-heading-title\">\n                                                Aya Mohamed                                            <\/h5>\n                                        <\/a>\n                                        <span class=\"iq-specialized\">\n                                            Speech Therapist                                        <\/span>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                            <div class=\"col-lg-4 col-md-6\">\n                            <div class=\"iq-team-blog animated fadeInUp speech-therapist blogBox moreBox\">\n                            \n                                                                    <div class=\"kivicare-project-image\">\n                                        <img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Shaimaa-Hassan.png\" alt=\"iqonic-casestudy\"\/>                                    <\/div>\n                                \n                                <div class=\"share iq-team-social\">\n                                    <ul>\n                                                                            <\/ul>\n                                <\/div>\n                                <div class=\"iq-team-info\">\n                                    <div class=\"iq-team-main-detail\">\n                                        <a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/shaimaa-hassan\/\">\n                                            <h5 class=\"member-text iq-heading-title\">\n                                                Shaimaa Hassan                                            <\/h5>\n                                        <\/a>\n                                        <span class=\"iq-specialized\">\n                                            Speech Therapist                                        <\/span>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                   <\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"hf-elementor-layout elementor-element elementor-element-cb8cdd8 elementor-widget elementor-widget-team\" data-id=\"cb8cdd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"iq-team iq-team-slider  iq-team-style-2 \">\n\t\t\t<div class=\"owl-carousel\" data-dots=\"true\" data-nav=\"true\" data-items=\"3\" data-items-laptop=\"3\" data-items-tab=\"2\" data-items-mobile=\"1\" data-items-mobile-sm=\"1\" data-autoplay=\"true\" data-loop=\"true\" data-margin=\"\" data-doteach=\"\" data-centermode=\"false\">\n\t\t\t\t\n\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t<div class=\"iq-team-blog\">\n\t\t\t\t\t\t\t\t<div class=\"iq-team-img\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Heba-Tarek-Naguib.png\" alt=\"team-image\"\/>\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"share iq-team-social\">\n\t\t\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"iq-team-info\">\n\t\t\t\t\t\t\t\t\t<div class=\"iq-team-main-detail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/heba-tarek-naguib\/\">\n\t\t\t\t\t\t\t\t\t\t\t<h5 class=\"member-text iq-heading-title\">\n\t\t\t\t\t\t\t\t\t\t\t\tHeba Tarek Naguib\t\t\t\t\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<span class=\"iq-specialized\">\n\t\t\t\t\t\t\t\t\t\t\tPsychologist\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div> \n\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t<div class=\"iq-team-blog\">\n\t\t\t\t\t\t\t\t<div class=\"iq-team-img\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Aya-Mohamed.png\" alt=\"team-image\"\/>\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"share iq-team-social\">\n\t\t\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"iq-team-info\">\n\t\t\t\t\t\t\t\t\t<div class=\"iq-team-main-detail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/aya-mohamed\/\">\n\t\t\t\t\t\t\t\t\t\t\t<h5 class=\"member-text iq-heading-title\">\n\t\t\t\t\t\t\t\t\t\t\t\tAya Mohamed\t\t\t\t\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<span class=\"iq-specialized\">\n\t\t\t\t\t\t\t\t\t\t\tSpeech Therapist\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div> \n\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t<div class=\"iq-team-blog\">\n\t\t\t\t\t\t\t\t<div class=\"iq-team-img\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Shaimaa-Hassan.png\" alt=\"team-image\"\/>\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"share iq-team-social\">\n\t\t\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"iq-team-info\">\n\t\t\t\t\t\t\t\t\t<div class=\"iq-team-main-detail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/shaimaa-hassan\/\">\n\t\t\t\t\t\t\t\t\t\t\t<h5 class=\"member-text iq-heading-title\">\n\t\t\t\t\t\t\t\t\t\t\t\tShaimaa Hassan\t\t\t\t\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<span class=\"iq-specialized\">\n\t\t\t\t\t\t\t\t\t\t\tSpeech Therapist\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div> \n\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t<div class=\"iq-team-blog\">\n\t\t\t\t\t\t\t\t<div class=\"iq-team-img\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Yassmin-Kordy.jpeg\" alt=\"team-image\"\/>\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"share iq-team-social\">\n\t\t\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"iq-team-info\">\n\t\t\t\t\t\t\t\t\t<div class=\"iq-team-main-detail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/yassmin-kordy\/\">\n\t\t\t\t\t\t\t\t\t\t\t<h5 class=\"member-text iq-heading-title\">\n\t\t\t\t\t\t\t\t\t\t\t\tYassmin Kordy\t\t\t\t\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<span class=\"iq-specialized\">\n\t\t\t\t\t\t\t\t\t\t\tNeuropsychology\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div> \n\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t<div class=\"iq-team-blog\">\n\t\t\t\t\t\t\t\t<div class=\"iq-team-img\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/backup.the360clinics.com\/the360clinics\/wp-content\/uploads\/2025\/05\/Mustafa-Hassaballah.png\" alt=\"team-image\"\/>\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"share iq-team-social\">\n\t\t\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"iq-team-info\">\n\t\t\t\t\t\t\t\t\t<div class=\"iq-team-main-detail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/backup.the360clinics.com\/the360clinics\/team\/mustafa-hassaballah\/\">\n\t\t\t\t\t\t\t\t\t\t\t<h5 class=\"member-text iq-heading-title\">\n\t\t\t\t\t\t\t\t\t\t\t\tMustafa Hassaballah\t\t\t\t\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<span class=\"iq-specialized\">\n\t\t\t\t\t\t\t\t\t\t\tNeuropsychology\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div> \t\t\t<\/div>\n\t\t<\/div> \n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Doctors Best Specialist Doctors Our Team All Academic Advisor Biophysical Business Development Clinical Psychologist Neuropsychology Psychiatrist Psychologist Psychotherapist Speech Therapist Heba Tarek Naguib Psychologist Aya Mohamed Speech Therapist Shaimaa Hassan Speech Therapist Yassmin Kordy Neuropsychology Mustafa Hassaballah Neuropsychology Nada Nakhla Psychotherapist Salma El Behary Neuropsychology Malak El Dessouki Biophysical Shahd Fouad Clinical Psychologist Aya Azzam [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1779","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/backup.the360clinics.com\/the360clinics\/wp-json\/wp\/v2\/pages\/1779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/backup.the360clinics.com\/the360clinics\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/backup.the360clinics.com\/the360clinics\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/backup.the360clinics.com\/the360clinics\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/backup.the360clinics.com\/the360clinics\/wp-json\/wp\/v2\/comments?post=1779"}],"version-history":[{"count":7,"href":"https:\/\/backup.the360clinics.com\/the360clinics\/wp-json\/wp\/v2\/pages\/1779\/revisions"}],"predecessor-version":[{"id":39960,"href":"https:\/\/backup.the360clinics.com\/the360clinics\/wp-json\/wp\/v2\/pages\/1779\/revisions\/39960"}],"wp:attachment":[{"href":"https:\/\/backup.the360clinics.com\/the360clinics\/wp-json\/wp\/v2\/media?parent=1779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}